{"id":1986,"date":"2024-11-20T12:21:26","date_gmt":"2024-11-20T12:21:26","guid":{"rendered":"https:\/\/granadilladeabona.app\/?p=1986"},"modified":"2024-12-11T19:34:26","modified_gmt":"2024-12-11T19:34:26","slug":"casa-de-los-guimera","status":"publish","type":"post","link":"https:\/\/granadilladeabona.app\/de\/casa-de-los-guimera\/","title":{"rendered":"Casa de Los Guimer\u00e1"},"content":{"rendered":"\n<p class=\"has-large-font-size wp-block-paragraph\"><strong><em>Das \u00e4lteste Haus des Dorfes stammt aus dem 16. Jahrhundert und wurde im 19. und 20. Jahrhundert als Tabaktrockner genutzt.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach der Eroberung geh\u00f6rte Las Vegas zun\u00e4chst dem Herzog von Medina-Sidonia, ging dann in den Besitz des Basken Juan de Gordejuela \u00fcber und sp\u00e4ter an die Augustinerinnen des Klosters San Andr\u00e9s und Santa M\u00f3nica, das die Familie Gordejuela in Los Realejos gegr\u00fcndet hatte. Ab dem 19. Jahrhundert war die aus Tarragona stammende Familie Guimer\u00e1 am einflussreichsten, die im Zuge der Beschlagnahmung von Kircheng\u00fctern bedeutende Besitzt\u00fcmer erwarb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es hei\u00dft, dass Agust\u00edn Guimer\u00e1 i Ram\u00f3n, ein Schiffskapit\u00e4n und Begr\u00fcnder dieser Familiensaga, bei seiner Ankunft auf Teneriffa im Jahr 1824 fast Schiffbruch erlitt, sein Schiff verkaufte und auf der Insel blieb. Seinen Nachkommen zufolge war er es, der die Glocke des Schiffes als Glockenturm an der Pinie vor der Kapelle aufh\u00e4ngte, obwohl die heutige Glocke nicht die urspr\u00fcngliche ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Geb\u00e4ude wurde mehrfach genutzt, unter anderem als Trockenschuppen. Die Tabakbl\u00e4tter wurden auf Querbalken, den so genannten mancuernas, gelagert und zur besseren Bel\u00fcftung in Gruppen von Bl\u00e4ttern aufgeteilt. F\u00fcr eine gute Trocknung war es notwendig, dass das Geb\u00e4ude nicht zu feucht und gut bel\u00fcftet war.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das \u00e4lteste Haus des Dorfes stammt aus dem 16. Jahrhundert und wurde im 19. und 20. Jahrhundert als Tabaktrockner genutzt. Nach der Eroberung geh\u00f6rte Las Vegas zun\u00e4chst dem Herzog von Medina-Sidonia, ging dann in den Besitz des Basken Juan de Gordejuela \u00fcber und sp\u00e4ter an die Augustinerinnen des Klosters San Andr\u00e9s und Santa M\u00f3nica, das [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":1737,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[109,111,113,115],"class_list":["post-1986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert","tag-pr-tf83-1-de","tag-pr-tf83-2-de","tag-pr-tf83-3-de","tag-pr-tf83-4-de"],"_links":{"self":[{"href":"https:\/\/granadilladeabona.app\/de\/wp-json\/wp\/v2\/posts\/1986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granadilladeabona.app\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granadilladeabona.app\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granadilladeabona.app\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/granadilladeabona.app\/de\/wp-json\/wp\/v2\/comments?post=1986"}],"version-history":[{"count":1,"href":"https:\/\/granadilladeabona.app\/de\/wp-json\/wp\/v2\/posts\/1986\/revisions"}],"predecessor-version":[{"id":1987,"href":"https:\/\/granadilladeabona.app\/de\/wp-json\/wp\/v2\/posts\/1986\/revisions\/1987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/granadilladeabona.app\/de\/wp-json\/wp\/v2\/media\/1737"}],"wp:attachment":[{"href":"https:\/\/granadilladeabona.app\/de\/wp-json\/wp\/v2\/media?parent=1986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granadilladeabona.app\/de\/wp-json\/wp\/v2\/categories?post=1986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granadilladeabona.app\/de\/wp-json\/wp\/v2\/tags?post=1986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}